{"id":1361,"date":"2021-06-14T10:01:28","date_gmt":"2021-06-14T13:01:28","guid":{"rendered":"https:\/\/blogpushmatcha.com.br\/?p=1361"},"modified":"2021-08-02T15:43:46","modified_gmt":"2021-08-02T18:43:46","slug":"barra-gelada-de-matcha-e-coco","status":"publish","type":"post","link":"https:\/\/blogpushmatcha.com.br\/index.php\/2021\/06\/14\/barra-gelada-de-matcha-e-coco\/","title":{"rendered":"Barra Gelada de Matcha e Coco"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ingredientes<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>4 col de sopa de manteiga de coco derretida<\/li><li>5 gotas de extrato caramel stevia<\/li><li>1 col de ch\u00e1 cheia de match\u00e1 em p\u00f3<\/li><li>Chips de coco queimado para decorar<\/li><li>Prote\u00edna sem sabor (opcional) ou sabor vanilla<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Modo de preparo<\/h2>\n\n\n\n<p>derreta a manteiga de coco em banho maria. Depois misture com a st\u00e9via, o matcha e a prote\u00edna se desejar. Coloque em forminhas de silicone e coco chips em cima para decorar ( ou pode usar berries desidratadas, cacau nibs..) Leve ao congelador por no m\u00ednimo 1h30min! PRONTO!<\/p>\n\n\n\n<p><br><br>Ficou com vontade de fazer essa receita?&nbsp;<a href=\"https:\/\/www.pushmatcha.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a>&nbsp;para acessar nosso site e compre o melhor matcha do Brasil!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes 4 col de sopa de manteiga de coco derretida 5 gotas de extrato caramel stevia 1 col de ch\u00e1 cheia de match\u00e1 em p\u00f3 Chips de coco queimado para decorar Prote\u00edna sem sabor (opcional) ou sabor vanilla Modo de preparo derreta a manteiga de coco em banho maria. Depois misture com a st\u00e9via, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[63,64,44,65],"class_list":["post-1361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-barra-gelada","tag-coco","tag-matcha","tag-protein"],"acf":[],"_links":{"self":[{"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1361"}],"version-history":[{"count":6,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1361\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1361\/revisions\/1655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/media\/1362"}],"wp:attachment":[{"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogpushmatcha.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}